{"id":6115,"date":"2021-10-18T15:55:21","date_gmt":"2021-10-18T15:55:21","guid":{"rendered":"http:\/\/rancholacienega.com\/ecoturismo\/?p=6115"},"modified":"2022-01-17T22:26:30","modified_gmt":"2022-01-17T22:26:30","slug":"sierra-fria","status":"publish","type":"post","link":"https:\/\/rancholacienega.com\/ecoturismo\/BLOG\/sierra-fria\/","title":{"rendered":"SIERRA FRIA"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"6115\" class=\"elementor elementor-6115\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-c6dc048 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"98106\" data-id=\"c6dc048\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1c70d69\" data-eae-slider=\"21490\" data-id=\"1c70d69\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a0b5c4 elementor-widget elementor-widget-heading\" data-id=\"7a0b5c4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bf Qu\u00e9 es SIERRA FR\u00cdA ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-efcbb67 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"71015\" data-id=\"efcbb67\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c01c7c4\" data-eae-slider=\"92410\" data-id=\"c01c7c4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73cc19e elementor-widget elementor-widget-text-editor\" data-id=\"73cc19e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"line-height: 18.345600128173828px; font-size: 15.288000106811523px; font-family: Arial; caret-color: #000000; color: #000000; text-align: justify;\">El Es<\/span><span style=\"line-height: 18.345600128173828px; font-size: 15.288000106811523px; font-family: Arial; caret-color: #000000; color: #000000; text-align: justify;\">tado de Aguascalientes cuenta con una superficie de 561,779.829 has. de las cuales\u00a0<\/span><span style=\"line-height: 18.345600128173828px; font-size: 15.288000106811523px; font-family: Arial; caret-color: #000000; color: #000000; text-align: justify;\">189,562 ha<\/span><span style=\"line-height: 18.345600128173828px; font-size: 15.288000106811523px; font-family: Arial; caret-color: #000000; color: #000000; text-align: justify;\">s.<\/span><span style=\"line-height: 18.345600128173828px; font-size: 15.288000106811523px; font-family: Arial; caret-color: #000000; color: #000000; text-align: justify;\">\u00a0<\/span><span style=\"line-height: 18.345600128173828px; font-size: 15.288000106811523px; font-family: Arial; caret-color: #000000; color: #000000; text-align: justify;\">pertenecen a superficie forestal, \u00a0siendo el\u00a0<\/span><span style=\"line-height: 18.345600128173828px; font-size: 15.288000106811523px; font-family: Arial; caret-color: #000000; color: #000000; text-align: justify;\">33.74 % de la superficie total estatal, los bosques ocupan 65,447 h<\/span><span style=\"line-height: 18.345600128173828px; font-size: 15.288000106811523px; font-family: Arial; caret-color: #000000; color: #000000; text-align: justify;\">as. (34.52 %), \u00a0124,115 has. que comprende la\u00a0<\/span><span style=\"line-height: 18.345600128173828px; font-size: 15.288000106811523px; font-family: Arial; caret-color: #000000; color: #000000; text-align: justify;\">vegetaci\u00f3n<\/span><span style=\"line-height: 18.345600128173828px; font-size: 15.288000106811523px; font-family: Arial; caret-color: #000000; color: #000000; text-align: justify;\">\u00a0de zonas \u00e1ridas, de las cuales<\/span><span style=\"line-height: 18.345600128173828px; font-size: 15.288000106811523px; font-family: Arial; caret-color: #000000; color: #000000; text-align: justify;\">\u00a080,925 has<\/span><span style=\"line-height: 18.345600128173828px; font-size: 15.288000106811523px; font-family: Arial; caret-color: #000000; color: #000000; text-align: justify;\">. se encuentran en condiciones de regular a ligeramente degradadas,\u00a0<\/span><span style=\"line-height: 18.345600128173828px; font-size: 15.288000106811523px; font-family: Arial; caret-color: #000000; color: #000000; text-align: justify;\">y\u00a0<\/span><span style=\"line-height: 18.345600128173828px; font-size: 15.288000106811523px; font-family: Arial; caret-color: #000000; color: #000000; text-align: justify;\">43,190 has.\u00a0<\/span><span style=\"line-height: 18.345600128173828px; font-size: 15.288000106811523px; font-family: Arial; caret-color: #000000; color: #000000; text-align: justify;\">perturbadas.<\/span><\/p><p><span style=\"line-height: 18.345600128173828px; font-size: 15.288000106811523px; font-family: Arial; caret-color: #000000; color: #000000; text-align: justify;\"><span style=\"text-align: start; font-size: 11pt; line-height: 16.866666793823242px; font-family: Arial, sans-serif;\">Geogr\u00e1ficamente Sierra Fr\u00eda se ubica al\u00a0\u00a0noroeste del estado de Aguascalientes entre los 22\u00ba27\u201931.99\u201d y 21\u00ba56\u201911.12\u201d de Latitud Norte, y los 102\u00ba41\u201934.56\u201d y 102\u00ba08\u2019 35.59\u201d de Longitud Oeste, siendo<\/span><\/span><span style=\"font-family: 'Times New Roman', serif; font-size: 12pt; caret-color: #000000; color: #000000; font-style: inherit;\">\u00a0un macizo monta\u00f1oso de clima seco-templado, rodeado de valles que <\/span><span style=\"font-family: 'Times New Roman', serif; font-size: 12pt; caret-color: #000000; color: #000000;\"><i>abarca una superficie aproximada a las 106,000 hect\u00e1reas<\/i><\/span><span style=\"font-family: 'Times New Roman', serif; font-size: 12pt; caret-color: #000000; color: #000000; font-style: inherit;\"> y que principalmente est\u00e1 cubierto por una capa vegetal de Pino-Encino, Encino-Manzanilla, Jun\u00edpero-Encino as\u00ed como una muy amplia diversidad de fauna silvestre tales como Puma, Venado Cola Blanca, Jabal\u00ed de Collar, Guajolote Silvestre &#8220;Gould&#8221; y Aguila Real entre otros.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a046f4e elementor-widget elementor-widget-heading\" data-id=\"a046f4e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bf Qu\u00e9 es SIERRA FR\u00cdA AGUASCALIENTES, A.C. ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-2ddb5f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"33526\" data-id=\"2ddb5f2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e23071\" data-eae-slider=\"66708\" data-id=\"2e23071\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b63ca8e elementor-widget elementor-widget-image\" data-id=\"b63ca8e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"522\" height=\"223\" src=\"https:\/\/rancholacienega.com\/ecoturismo\/wp-content\/uploads\/2021\/10\/LOGO-SIERRA-FRIA-2.jpg\" class=\"attachment-large size-large wp-image-6068\" alt=\"\" srcset=\"https:\/\/rancholacienega.com\/ecoturismo\/wp-content\/uploads\/2021\/10\/LOGO-SIERRA-FRIA-2.jpg 522w, https:\/\/rancholacienega.com\/ecoturismo\/wp-content\/uploads\/2021\/10\/LOGO-SIERRA-FRIA-2-300x128.jpg 300w\" sizes=\"(max-width: 522px) 100vw, 522px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-eb689c5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"20461\" data-id=\"eb689c5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c8c8cb9\" data-eae-slider=\"21956\" data-id=\"c8c8cb9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b613da elementor-widget elementor-widget-heading\" data-id=\"1b613da\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Una semblanza hist\u00f3rica:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-de3e5f5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"35428\" data-id=\"de3e5f5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a43f26\" data-eae-slider=\"53757\" data-id=\"4a43f26\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fb0288 elementor-widget elementor-widget-text-editor\" data-id=\"3fb0288\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"margin: 0cm; font-size: medium; font-family: 'Times New Roman', serif; caret-color: #000000; color: #000000; font-style: normal; text-align: justify;\"><span lang=\"ES-TRAD\">Aguascalientes es uno de los Estados de la Rep\u00fablica Mexicana pioneros, en cuanto a Protecci\u00f3n, Conservaci\u00f3n y Vigilancia se refiere de un Ecosistema, iniciando labores en el a\u00f1o de 1975 con acciones concretas tendientes a la protecci\u00f3n del \u00e1rea gen\u00e9ricamente conocida como \u201cSierra Fr\u00eda\u201d, implementando un Programa de Estudio, Difusi\u00f3n y Vigilancia de los recursos naturales de flora y fauna, impulsado por un peque\u00f1o grupo, asociados a la Delegaci\u00f3n Estatal del <strong>Consejo Nacional de la Fauna, A.C<\/strong>., futuros asociados a\u00a0<strong>Sierra Fr\u00eda Aguascalientes, A.C.<\/strong>, operado y fielmente interpretado por un brillante aprendiz, siempre enamorado de la conservaci\u00f3n de la naturaleza y actualmente experto,\u00a0\u00a0gran conocedor de este precioso reducto y encargado de las labores de vigilancia dentro del Instituto del Medio Ambiente del Estado\u00a0<b>(IMAE)<\/b>, el <strong>Arq. Jos\u00e9 Agust\u00edn Medina Flores<\/strong>. Ahora con orgullo nuestra organizaci\u00f3n presenta este sitio para que sirva de ejemplo a los connacionales de nuestro lindo Pa\u00eds en el cuidado y acrecentamiento de una basta Biodiversidad por a\u00f1os celosamente guardada.<\/span><\/p><\/div><\/div><\/div><\/div><\/div><\/section><\/div> <a href=\"https:\/\/rancholacienega.com\/ecoturismo\/BLOG\/sierra-fria\/#more-6115\" class=\"more-link elementor-more-link\"><span aria-label=\"Continuar leyendo SIERRA FRIA\">(m\u00e1s&hellip;)<\/span><\/a>","protected":false},"excerpt":{"rendered":"<p>\u00bf Qu\u00e9 es SIERRA FR\u00cdA ? El Estado de Aguascalientes cuenta con una superficie de 561,779.829 has. de las cuales\u00a0189,562 has.\u00a0pertenecen a superficie forestal, \u00a0siendo el\u00a033.74 % de la superficie total estatal, los bosques ocupan 65,447 has. (34.52 %), \u00a0124,115 has. que comprende la\u00a0vegetaci\u00f3n\u00a0de zonas \u00e1ridas, de las cuales\u00a080,925 has. se encuentran en condiciones de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[168,303],"tags":[],"_links":{"self":[{"href":"https:\/\/rancholacienega.com\/ecoturismo\/wp-json\/wp\/v2\/posts\/6115"}],"collection":[{"href":"https:\/\/rancholacienega.com\/ecoturismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rancholacienega.com\/ecoturismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rancholacienega.com\/ecoturismo\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/rancholacienega.com\/ecoturismo\/wp-json\/wp\/v2\/comments?post=6115"}],"version-history":[{"count":34,"href":"https:\/\/rancholacienega.com\/ecoturismo\/wp-json\/wp\/v2\/posts\/6115\/revisions"}],"predecessor-version":[{"id":7327,"href":"https:\/\/rancholacienega.com\/ecoturismo\/wp-json\/wp\/v2\/posts\/6115\/revisions\/7327"}],"wp:attachment":[{"href":"https:\/\/rancholacienega.com\/ecoturismo\/wp-json\/wp\/v2\/media?parent=6115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rancholacienega.com\/ecoturismo\/wp-json\/wp\/v2\/categories?post=6115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rancholacienega.com\/ecoturismo\/wp-json\/wp\/v2\/tags?post=6115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}